{"id":22,"count":9,"description":"","link":"https:\/\/callindo.com\/en\/tag\/ai-in-telemarketing-indonesia\/","name":"AI in Telemarketing Indonesia","slug":"ai-in-telemarketing-indonesia","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/callindo.com\/en\/wp-json\/wp\/v2\/tags\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/callindo.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/callindo.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/callindo.com\/en\/wp-json\/wp\/v2\/posts?tags=22"},{"href":"https:\/\/callindo.com\/en\/wp-json\/wp\/v2\/successstory?tags=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}